{"id":23556,"date":"2021-05-07T13:40:21","date_gmt":"2021-05-07T11:40:21","guid":{"rendered":"https:\/\/xpatientbcncongress.com\/?p=23556"},"modified":"2021-08-30T14:18:53","modified_gmt":"2021-08-30T12:18:53","slug":"la-salud-digital-crece-exponencialmente-a-raiz-de-la-pandemia-de-la-covid-19","status":"publish","type":"post","link":"https:\/\/xpatientbcncongress.com\/es\/la-salud-digital-crece-exponencialmente-a-raiz-de-la-pandemia-de-la-covid-19\/","title":{"rendered":"La salud digital crece exponencialmente a ra\u00edz de la pandemia de la Covid-19"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>El congreso XPatient Barcelona Congress dedicar\u00e1 una mesa redonda a los aprendizajes de la Covid-19 y al papel de la tecnolog\u00eda para ayudar a hacer frente a la pandemia.<\/li><li>El Hospital Cl\u00ednic ha llegado a 175.402 visitas m\u00e9dicas telef\u00f3nicas en 2020.<\/li><li>La promoci\u00f3n de la prevenci\u00f3n, la monitorizaci\u00f3n, la comunicaci\u00f3n y el apoyo a la decisi\u00f3n son algunas de las principales ventajas que ofrece la salud digital.<\/li><\/ul>\n\n\n\n<p><strong><u>Barcelona, 7 de mayo de 2021.-<\/u><\/strong><strong> <\/strong>La salud digital ha experimentado un crecimiento exponencial en el \u00faltimo a\u00f1o a ra\u00edz de la pandemia de la Covid-19, tanto a nivel de visitas m\u00e9dicas como en el \u00e1rea de enfermer\u00eda, demostrando su eficacia en aspectos como la modelizaci\u00f3n de los procesos cl\u00ednicos, la promoci\u00f3n de la prevenci\u00f3n, la monitorizaci\u00f3n y el apoyo a la decisi\u00f3n.<\/p>\n\n\n\n<p>Este fen\u00f3meno ser\u00e1 uno de los aspectos que se tratar\u00e1n en la mesa redonda \u201cCovid-19-Qu\u00e9 hemos aprendido y c\u00f3mo la tecnolog\u00eda nos ayuda\u201d, que tendr\u00e1 lugar en el marco de la sexta edici\u00f3n del congreso XPatient Barcelona Congress, organizado por el centro tecnol\u00f3gico Eurecat, el Hospital Cl\u00ednic de Barcelona y la Fundaci\u00f3 TIC Salut Social, con el impulso de la comunidad de pr\u00e1ctica XPA Barcelona (Experiencia del Paciente).<\/p>\n\n\n\n<p>En palabras del doctor Raimon Camps, coordinador de Experiencia del Paciente en Hospital Cl\u00ednic sede Plat\u00f3-AISBE, el \u00c1rea de Reporting del Hospital Cl\u00ednic ha constatado \u201cun aumento espectacular de las visitas m\u00e9dicas no presenciales\u201d, dado que durante 2019 la inmensa mayor\u00eda de las visitas ambulatorias eran presenciales y en 2020 se han hecho 175.402 visitas telef\u00f3nicas, lo cual representa m\u00e1s del 40 por ciento de las segundas visitas realizadas en consultas externas.<\/p>\n\n\n\n<p>En cuanto a las de enfermer\u00eda, se ha pasado de 51.474 a 90.948 visitas en remoto, una diferencia que representa un aumento del 77 por ciento.<\/p>\n\n\n\n<p>De acuerdo con el director de Digital Health de Eurecat, Felip Miralles, la Covid-19 \u201cha acelerado la implantaci\u00f3n de nuevas herramientas y de nuevos medios para poder tratar a los pacientes en todas sus fases\u201d, abarcando desde la prevenci\u00f3n de contagios, el diagn\u00f3stico precoz y la trazabilidad hasta el seguimiento y la atenci\u00f3n domiciliaria y las posibles transiciones del domicilio al hospital y a la inversa.<\/p>\n\n\n\n<p>Asimismo, explica, \u201ca partir de todos los datos que se recogen es posible proveer de herramientas de apoyo a la decisi\u00f3n, m\u00e1s informadas, en tiempo real y que hagan posible una gesti\u00f3n de la salud mucho m\u00e1s basada en los datos y no tanto en la intuici\u00f3n\u201d. Un ejemplo en este apartado, destaca, \u201ces la herramienta Proceed en t\u00e9cnicas de Inteligencia Artificial a partir de datos heterog\u00e9neos que permite predecir a 21 d\u00edas c\u00f3mo evolucionar\u00e1 la incidencia de la Covid-19, tasas de contagio, ingresos y ocupaci\u00f3n en hospitales y UCIs\u201d.<\/p>\n\n\n\n<p>\u201cLa pandemia ha obligado a adaptar las herramientas para evaluar la experiencia de pacientes. Durante el 2020 se han realizado 29 grupos focales a trav\u00e9s de videoconferencia con m\u00e1s de 200 pacientes y profesionales implicados y se han realizado actividades abiertas en la red con m\u00e1s de 2.500 participantes\u201d, seg\u00fan el Dr. Joan Escarrabill, de la comunidad de pr\u00e1ctica XPA Barcelona (Experiencia de Paciente) y del equipo de Experiencia de Pacientes del Hospital Cl\u00ednic.<\/p>\n\n\n\n<p>Desde la Fundaci\u00f3 TIC Salut Social, su director, Josu\u00e8 Sallent, explica que \u201csi bien durante los \u00faltimos a\u00f1os ha ido evolucionando el proceso de transformaci\u00f3n digital en el pa\u00eds y m\u00e1s concretamente en el sector salud, la Covid-19 ha acelerado a\u00fan m\u00e1s el ritmo de cambio y la velocidad de la transformaci\u00f3n y esto ha obligado a fomentar herramientas de videoconsultas, as\u00ed como otros servicios no presenciales\u201d.<\/p>\n\n\n\n<p>En este periodo de tiempo, subraya, \u201ctodos hemos tenido que responder de una manera casi inmediata, sin perder de vista el resto de aspectos y pacientes con otras patolog\u00edas m\u00e9dicas de nuestro pa\u00eds. De hecho, actualmente, hay el 47 por ciento de los hospitales p\u00fablicos de Catalu\u00f1a, concretamente 31 de un total de 66, que est\u00e1n adheridos a la herramienta corporativa de videoconsulta del Servei Catal\u00e0 de Salut y se espera que vayan en aumento\u201d.<\/p>\n\n\n\n<p>Seg\u00fan se\u00f1ala Carolina Garcia-Vidal, especialista senior del Servicio de Enfermedades Infecciosas del Hospital Cl\u00ednic, \u201cen un momento de pandemia por un virus nuevo que afecta a un n\u00famero muy elevado de la poblaci\u00f3n y produce una enfermedad que es desconocida, tener el control de todo lo que est\u00e1 pasando en tiempo real es b\u00e1sico\u201d.<\/p>\n\n\n\n<p>Bajo este concepto, \u201cdesde el Hospital Cl\u00ednic apostamos por la innovaci\u00f3n y el desarrollo de tecnolog\u00eda para apoyar a los m\u00e9dicos en su lucha frente a la Covid-19 y creamos un centro de control de pacientes con Covid, con informaci\u00f3n en tiempo real de los fenotipos cl\u00ednicos de los pacientes ayudando a que estos pudieran recibir un tratamiento precoz y personalizado con unos resultados excelentes\u201d, expone.<\/p>\n\n\n\n<p>La pandemia de la Covid-19 \u201cnos ha hecho adaptar nuestra manera de atender a las personas de una forma muy r\u00e1pida\u201d, remarca Silvia Roura Rovira, adjunta a Gerencia de CAPSBE, para quien \u201clas nuevas tecnolog\u00edas han sido claves y han entrado con fuerza\u201d.<\/p>\n\n\n\n<p>En su opini\u00f3n, \u201cla consulta virtual, la telef\u00f3nica y la videoconsulta han demostrado que podemos seguir manteniendo nuestra calidad asistencial y ser eficaces en la resoluci\u00f3n de las necesidades de las personas que atendemos\u201d.<\/p>\n\n\n\n<p>\u201cHemos aprendido que los equipos de atenci\u00f3n primaria tenemos una gran capacidad de adaptaci\u00f3n y resiliencia\u201d, por lo que \u201ctenemos que ser proactivos ante los procedimientos y protocolos, transmitiendo la informaci\u00f3n de forma clara a la poblaci\u00f3n y sobre todo ser \u00e1giles ante los cambios\u201d, contin\u00faa Silvia Roura, quien recalca que \u201cla campa\u00f1a de vacunaci\u00f3n que ha abierto la brecha de la esperanza\u201d.<\/p>\n\n\n\n<p>Esta nueva edici\u00f3n del congreso XPatient Barcelona Congress, que tendr\u00e1 lugar el 28 y 29 de septiembre, pondr\u00e1 especial foco en c\u00f3mo la experiencia de la pandemia ha cambiado las percepciones y maneras de hacer en salud, y en el impacto que ha tenido la tecnolog\u00eda como aceleradora de procesos, con muchos aprendizajes en todos los niveles.<\/p>\n\n\n\n<p><strong>El Call for Projects del congreso est\u00e1 abierto a la participaci\u00f3n en este <\/strong><a href=\"https:\/\/xpatientbcncongress.com\/es\/call-for-projects-2\/\"><strong>link<\/strong><\/a><strong><\/strong><\/p>\n\n\n\n<p><strong>Pod\u00e9is ampliar la informaci\u00f3n o solicitar entrevistas al Gabinete de Prensa de Eurecat en el email premsa@eurecat.org o en el m\u00f3vil 630 425 169.<\/strong><\/p>\n\n\n\n<p><strong>Sobre Eurecat<\/strong><\/p>\n\n\n\n<p>Eurecat, Centro Tecnol\u00f3gico de Catalu\u00f1a, aglutina la experiencia de m\u00e1s de <strong>650 profesionales<\/strong> que generan un volumen de ingresos de <strong>50 millones de euros anuales<\/strong> y presta servicio a m\u00e1s de <strong>1.600 empresas<\/strong>. <strong>I+D aplicado<\/strong>, <strong>servicios tecnol\u00f3gicos<\/strong>, <strong>formaci\u00f3n de alta especializaci\u00f3n<\/strong>, <strong>consultor\u00eda tecnol\u00f3gica<\/strong> y <strong>eventos profesionales<\/strong> son algunos de los servicios que Eurecat ofrece tanto para grandes como para peque\u00f1as y medianas empresas de todos los sectores. Con instalaciones en Barcelona, Canet de Mar, Cerdanyola del Vall\u00e8s, Girona, Lleida, Manresa, Matar\u00f3, Reus, Tarragona, Amposta y Vila-seca, participa en <strong>160 grandes proyectos consorciados de I+D+i<\/strong> nacionales e internacionales de alto valor estrat\u00e9gico y cuenta con <strong>88 patentes<\/strong> y <strong>7 spin-off<\/strong>. El valor a\u00f1adido que aporta Eurecat <strong>acelera la innovaci\u00f3n<\/strong>, <strong>disminuye el gasto en infraestructuras<\/strong> cient\u00edficas y tecnol\u00f3gicas, <strong>reduce los riesgos <\/strong>y proporciona <strong>conocimiento especializado <\/strong>a medida de cada empresa. <strong>M\u00e1s informaci\u00f3n en <\/strong><a href=\"http:\/\/www.eurecat.org\"><strong>www.eurecat.org<\/strong><\/a><\/p>\n\n\n\n<p><strong><em>M\u00e1s informaci\u00f3n:<br><br><\/em><\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong>Montse Mascar\u00f3<br>Prensa | Direcci\u00f3n de Comunicaci\u00f3n Corporativa <\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong>Eurecat<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong>Tel. (+34) 932 381 400 | M\u00f3vil: (+34) 630 425 169<br>C\/e: premsa@eurecat.org | <\/strong><a href=\"http:\/\/www.eurecat.org\">www.eurecat.org<\/a><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El congreso XPatient Barcelona Congress dedicar\u00e1 una mesa redonda a los aprendizajes de la Covid-19 y al papel de la tecnolog\u00eda para ayudar a hacer frente a la pandemia. El Hospital Cl\u00ednic ha llegado a 175.402 visitas m\u00e9dicas telef\u00f3nicas en 2020. La promoci\u00f3n de la prevenci\u00f3n, la monitorizaci\u00f3n, la comunicaci\u00f3n y el apoyo a la&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/xpatientbcncongress.com\/es\/la-salud-digital-crece-exponencialmente-a-raiz-de-la-pandemia-de-la-covid-19\/\" class=\"gdlr-info-font excerpt-read-more\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":23562,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[858],"tags":[],"class_list":["post-23556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ndp_2021_previa_ca-es"],"_links":{"self":[{"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/posts\/23556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/comments?post=23556"}],"version-history":[{"count":5,"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/posts\/23556\/revisions"}],"predecessor-version":[{"id":23572,"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/posts\/23556\/revisions\/23572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/media\/23562"}],"wp:attachment":[{"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/media?parent=23556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/categories?post=23556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xpatientbcncongress.com\/es\/wp-json\/wp\/v2\/tags?post=23556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}